{"id":70362,"date":"2017-11-11T22:00:56","date_gmt":"2017-11-11T21:00:56","guid":{"rendered":"http:\/\/www.fanselanchalon.fr\/v3\/?p=70362"},"modified":"2017-11-11T22:00:56","modified_gmt":"2017-11-11T21:00:56","slug":"le-cauchemar-continue","status":"publish","type":"post","link":"https:\/\/www.fanselanchalon.fr\/v3\/archives\/70362","title":{"rendered":"Le cauchemar continue"},"content":{"rendered":"<p><a href=\"http:\/\/www.fanselanchalon.fr\/v3\/wp-content\/uploads\/2017\/11\/cholet.jpg\" data-rel=\"lightbox-image-0\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-70368 aligncenter\" src=\"http:\/\/www.fanselanchalon.fr\/v3\/wp-content\/uploads\/2017\/11\/cholet.jpg\" alt=\"\" width=\"692\" height=\"596\" srcset=\"https:\/\/www.fanselanchalon.fr\/v3\/wp-content\/uploads\/2017\/11\/cholet.jpg 692w, https:\/\/www.fanselanchalon.fr\/v3\/wp-content\/uploads\/2017\/11\/cholet-595x512.jpg 595w, https:\/\/www.fanselanchalon.fr\/v3\/wp-content\/uploads\/2017\/11\/cholet-520x448.jpg 520w\" sizes=\"auto, (max-width: 692px) 100vw, 692px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>C&rsquo;\u00e9tait le match des mal class\u00e9s, Chalon (1 victoire) se d\u00e9pla\u00e7ait \u00e0 Cholet (2 victoires). Malheureusement l&rsquo;Elan s&rsquo;incline une nouvelle fois et s&rsquo;enlise en bas de classement.<\/p>\n<p>&nbsp;<\/p>\n<p>Apr\u00e8s un d\u00e9part de match catastrophique, entre balles perdues, \u00ab\u00a0airballs\u00a0\u00bb et rebonds laiss\u00e9s \u00e0 l&rsquo;adversaire Chalon vire avec 8 points de retard apr\u00e8s 10 minutes de jeu. Et cela aurait pu \u00eatre pire car Dorsey r\u00e9ussissait son shoot du milieu de terrain au buzzer.<\/p>\n<p>&nbsp;<\/p>\n<p>Lors du second quart, on sent un l\u00e9ger mieux dans l&rsquo;\u00e9quipe, avec un bon passage de Boukichou. En remportant ce quart 18 \u00e0 17, Chalon rentre \u00e0 la pause avec 7 points de retard 37 \u00e0 30.<\/p>\n<p>&nbsp;<\/p>\n<p>Au retour des vestiaires, Cholet inflige un 9-0 d&rsquo;entr\u00e9e&#8230; Chalon est repouss\u00e9 \u00e0 16 puis 18 longueurs&#8230;\u00a0 Avec le retour de Rozenfeld sur le terrain et un premier coup de chaud de Farr Chalon ne l\u00e2che pas et recolle \u00e0 la fin du 3\u00e8me acte : 53 &#8211; 45.<\/p>\n<p>&nbsp;<\/p>\n<p>L&rsquo;Elan ne l\u00e2chait rien, et mettait la pression d&rsquo;entr\u00e9e sur les locaux. Avec un peu d&rsquo;adresse retrouv\u00e9e \u00e0 l&rsquo;ext\u00e9rieur par Farr notamment, quelques paniers de Nzeulie et Boukichou Chalon \u00e9galisait 60 \u00e0 60 \u00e0 quelques minutes de la fin. On pouvait esp\u00e9rer le holdup dans un match de \u00ab\u00a0tra\u00eenard\u00a0\u00bb, mais Michineau mettait un triple, puis Evans et Boutsiele par deux fois scellaient la fin du match : 70 \/ 64.<\/p>\n<p>&nbsp;<\/p>\n<p>Le cauchemar continue pour l&rsquo;Elan. Une victoire contre Hy\u00e8res-Toulon samedi prochain devient imp\u00e9rative pour arr\u00eater de broyer du noir&#8230; Allez l&rsquo;Elan ! Supporters tous au Colis\u00e9e !<\/p>\n<p>&nbsp;<\/p>\n<p>[AdSense-A]<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; C&rsquo;\u00e9tait le match des mal class\u00e9s, Chalon (1 victoire) se d\u00e9pla\u00e7ait \u00e0 Cholet (2 victoires). Malheureusement l&rsquo;Elan s&rsquo;incline une nouvelle fois et s&rsquo;enlise en bas de classement. &nbsp; Apr\u00e8s&hellip; <\/p>\n","protected":false},"author":100,"featured_media":70368,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"two_page_speed":[],"footnotes":""},"categories":[1],"tags":[406,50,57],"class_list":["post-70362","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-406","tag-cholet","tag-defaite"],"featured_image_src":"https:\/\/www.fanselanchalon.fr\/v3\/wp-content\/uploads\/2017\/11\/cholet.jpg","author_info":{"display_name":"Goof","author_link":"https:\/\/www.fanselanchalon.fr\/v3\/archives\/author\/goof71"},"_links":{"self":[{"href":"https:\/\/www.fanselanchalon.fr\/v3\/wp-json\/wp\/v2\/posts\/70362","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fanselanchalon.fr\/v3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fanselanchalon.fr\/v3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fanselanchalon.fr\/v3\/wp-json\/wp\/v2\/users\/100"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fanselanchalon.fr\/v3\/wp-json\/wp\/v2\/comments?post=70362"}],"version-history":[{"count":0,"href":"https:\/\/www.fanselanchalon.fr\/v3\/wp-json\/wp\/v2\/posts\/70362\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fanselanchalon.fr\/v3\/wp-json\/wp\/v2\/media\/70368"}],"wp:attachment":[{"href":"https:\/\/www.fanselanchalon.fr\/v3\/wp-json\/wp\/v2\/media?parent=70362"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fanselanchalon.fr\/v3\/wp-json\/wp\/v2\/categories?post=70362"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fanselanchalon.fr\/v3\/wp-json\/wp\/v2\/tags?post=70362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}